{"id":20276,"date":"2024-04-21T14:59:34","date_gmt":"2024-04-21T05:59:34","guid":{"rendered":"https:\/\/www.jacgg.com\/?p=20276"},"modified":"2024-05-15T20:44:19","modified_gmt":"2024-05-15T11:44:19","slug":"%e5%85%83%e5%9b%bd%e9%80%a3%e4%ba%8b%e5%8b%99%e6%ac%a1%e9%95%b7%e8%a3%9c%e3%81%ae%e3%83%93%e3%83%ab%e3%83%bb%e3%83%91%e3%83%88%e3%83%b3%e6%b0%8f%e3%81%af%e3%80%81%e3%82%ac%e3%82%b6%e3%81%a7%e3%81%ae","status":"publish","type":"post","link":"https:\/\/www.jacgg.com\/fr\/2024\/04\/21\/20276\/","title":{"rendered":"Un ancien sous-secr\u00e9taire g\u00e9n\u00e9ral des Nations unies, M. Bill Paton, affirme que la guerre \u00e0 Gaza met \u00e0 nu, une fois de plus, l&#8217;effroyable arbitraire de la justice internationale. (21\/4\/2024)"},"content":{"rendered":"<p><a href=\"http:\/\/www.jacgg.com\/wp-content\/uploads\/2024\/04\/795316b92fc766b0181f6fef074f03fa.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20277 aligncenter\" src=\"http:\/\/www.jacgg.com\/wp-content\/uploads\/2024\/04\/795316b92fc766b0181f6fef074f03fa.png\" alt=\"\" width=\"390\" height=\"235\" \/><\/a><\/p>\n<p class=\"Default\"><span lang=\"EN-US\">Un ancien sous-secr\u00e9taire g\u00e9n\u00e9ral des Nations unies, M. Bill Paton, affirme que la guerre \u00e0 Gaza met \u00e0 nu, une fois de plus, l&#8217;effroyable arbitraire de la justice internationale. L&#8217;\u00c9tat de droit international a toujours \u00e9t\u00e9 le fait des grandes puissances. Si nous voulons un monde plus juste et plus pacifique, les pays en d\u00e9veloppement &#8211; qui constituent la majorit\u00e9 de la population mondiale &#8211; doivent se lever et exiger une seule loi pour tous. <\/span><\/p>\n<p class=\"Default\"><span lang=\"EN-US\">Veuillez cliquer <a href=\"http:\/\/www.jacgg.com\/wp-content\/uploads\/2024\/04\/70f4980539985552029a513508a03a23.docx\">ici<\/a> pour consulter l&#8217;int\u00e9gralit\u00e9 de son article. (21\/4\/202)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ancien sous-secr\u00e9taire g\u00e9n\u00e9ral des Nations unies, M. Bill Paton, affirme que la guerre \u00e0 Gaza met \u00e0 nu, une fois de plus, l&#8217;effroyable arbitraire de la justice internationale. L&#8217;\u00c9tat de droit international a toujours \u00e9t\u00e9 le fait des grandes puissances. Si nous voulons un monde plus juste et plus pacifique, les pays en d\u00e9veloppement &#8211; qui constituent la majorit\u00e9 de la population mondiale &#8211; doivent se lever et exiger une seule loi pour tous. <\/p>\n<p>Veuillez cliquer ici pour consulter l&#8217;int\u00e9gralit\u00e9 de son article. (21\/4\/202)<\/p>\n","protected":false},"author":1,"featured_media":20277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["ja","en","fr"],"languages":{"ja":{"title":true,"content":true,"excerpt":true},"en":{"title":true,"content":true,"excerpt":true},"fr":{"title":true,"content":true,"excerpt":true}}},"_links":{"self":[{"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/posts\/20276"}],"collection":[{"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/comments?post=20276"}],"version-history":[{"count":7,"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/posts\/20276\/revisions"}],"predecessor-version":[{"id":20345,"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/posts\/20276\/revisions\/20345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/media\/20277"}],"wp:attachment":[{"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/media?parent=20276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/categories?post=20276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jacgg.com\/fr\/wp-json\/wp\/v2\/tags?post=20276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}